{"id":8388,"date":"2023-12-01T21:11:54","date_gmt":"2023-12-02T00:11:54","guid":{"rendered":"https:\/\/toprelay.com.br\/?post_type=product&#038;p=8388"},"modified":"2024-01-15T18:01:36","modified_gmt":"2024-01-15T21:01:36","slug":"tra821-324-reles-auxiliares","status":"publish","type":"product","link":"https:\/\/toprelay.com.br\/en\/product\/tra821-324-reles-auxiliares\/","title":{"rendered":"TRA821.324 - Auxiliary Relays"},"content":{"rendered":"<table id=\"tablepress-396\" class=\"tablepress tablepress-id-396\">\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n<td class=\"column-1\">TRA821324<\/td>\n<td class=\"column-2\">Universal \u2013 Heavy Duty Line<\/td>\n<td class=\"column-3\">No<\/td>\n<td class=\"column-4\">5<\/td>\n<td class=\"column-5\">0008216247\/ 0005459205<br \/>\n0025424319<\/td>\n<td class=\"column-6\">Mercedes-Benz<\/td>\n<td class=\"column-7\"><\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n<td class=\"column-1\"><\/td>\n<td class=\"column-2\"><\/td>\n<td class=\"column-3\"><\/td>\n<td class=\"column-4\"><\/td>\n<td class=\"column-5\">243461\/ 371912<\/td>\n<td class=\"column-6\">Scania<\/td>\n<td class=\"column-7\"><\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n<td class=\"column-1\"><\/td>\n<td class=\"column-2\"><\/td>\n<td class=\"column-3\"><\/td>\n<td class=\"column-4\"><\/td>\n<td class=\"column-5\">1245710\/ 71701606<\/td>\n<td class=\"column-6\">Iveco<\/td>\n<td class=\"column-7\"><\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n<td class=\"column-1\"><\/td>\n<td class=\"column-2\"><\/td>\n<td class=\"column-3\"><\/td>\n<td class=\"column-4\"><\/td>\n<td class=\"column-5\">1519521<\/td>\n<td class=\"column-6\">Daf<\/td>\n<td class=\"column-7\"><\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n<td class=\"column-1\"><\/td>\n<td class=\"column-2\"><\/td>\n<td class=\"column-3\"><\/td>\n<td class=\"column-4\"><\/td>\n<td class=\"column-5\">5000084771<\/td>\n<td class=\"column-6\">Renault<\/td>\n<td class=\"column-7\"><\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n<td class=\"column-1\"><\/td>\n<td class=\"column-2\"><\/td>\n<td class=\"column-3\"><\/td>\n<td class=\"column-4\"><\/td>\n<td class=\"column-5\">1731201<\/td>\n<td class=\"column-6\">Faun<\/td>\n<td class=\"column-7\"><\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n<td class=\"column-1\"><\/td>\n<td class=\"column-2\"><\/td>\n<td class=\"column-3\"><\/td>\n<td class=\"column-4\"><\/td>\n<td class=\"column-5\"><\/td>\n<td class=\"column-6\">KHD, MAN<\/td>\n<td class=\"column-7\"><\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n<td class=\"column-1\"><\/td>\n<td class=\"column-2\"><\/td>\n<td class=\"column-3\"><\/td>\n<td class=\"column-4\"><\/td>\n<td class=\"column-5\"><\/td>\n<td class=\"column-6\">Neoplan<\/td>\n<td class=\"column-7\"><\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n<td class=\"column-1\"><\/td>\n<td class=\"column-2\"><\/td>\n<td class=\"column-3\"><\/td>\n<td class=\"column-4\"><\/td>\n<td class=\"column-5\">1245710<\/td>\n<td class=\"column-6\">Fiat<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>8213<\/p>\n<p>Universal \u2013 Heavy Duty Line<\/p>\n<p><strong>24V &#8211; 2x25A<\/strong><\/p>\n<p><span style=\"color: #008000;\">Doble Open Contact<\/span><\/p>\n<p>Rel\u00e9s Auxiliares | Rel\u00e9s Auxiliares | Auxiliary Relays<\/p>","protected":false},"excerpt":{"rendered":"<p>TRA821324 Universal Linha Pesada N\u00e3o 5 0008216247\/ 0005459205 0025424319 Mercedes-Benz 243461\/ 371912 Scania 1245710\/ 71701606 Iveco 1519521 Daf 5000084771 Renault 1731201 Faun KHD, MAN Neoplan 1245710 Fiat 8213 Universal Linha Pesada 24V &#8211; 2x25A Duplo Contato Aberto Rel\u00e9s Auxiliares | Rel\u00e9s Auxiliares | Auxiliary Relays<\/p>","protected":false},"featured_media":8408,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}}},"product_cat":[3305,3301],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TRA821.324 - Rel\u00e9s Auxiliares - Top Relay<\/title>\n<meta name=\"description\" content=\"A Top Relay \u00e9 uma empresa l\u00edder na ind\u00fastria de rel\u00e9s, especializada em projetar, desenvolver, fabricar e testar uma ampla gama de produtos automotivos, agr\u00edcolas e industriais. Com foco em inova\u00e7\u00e3o e qualidade, a empresa oferece solu\u00e7\u00f5es abrangentes em rel\u00e9s, incluindo Minirreles, Rel\u00e9s Auxiliares, Rel\u00e9s de Farol, Rel\u00e9s de Pisca, Rel\u00e9s de Placa, Rel\u00e9s Eletr\u00f4nicos e Rel\u00e9s Soquetados. Sua dedica\u00e7\u00e3o \u00e0 excel\u00eancia e expertise no setor a tornam a escolha ideal para atender \u00e0s necessidades de seus clientes no mundo automotivo e industrial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toprelay.com.br\/en\/product\/tra821-324-reles-auxiliares\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRA821.324 - Rel\u00e9s Auxiliares - Top Relay\" \/>\n<meta property=\"og:description\" content=\"A Top Relay \u00e9 uma empresa l\u00edder na ind\u00fastria de rel\u00e9s, especializada em projetar, desenvolver, fabricar e testar uma ampla gama de produtos automotivos, agr\u00edcolas e industriais. Com foco em inova\u00e7\u00e3o e qualidade, a empresa oferece solu\u00e7\u00f5es abrangentes em rel\u00e9s, incluindo Minirreles, Rel\u00e9s Auxiliares, Rel\u00e9s de Farol, Rel\u00e9s de Pisca, Rel\u00e9s de Placa, Rel\u00e9s Eletr\u00f4nicos e Rel\u00e9s Soquetados. Sua dedica\u00e7\u00e3o \u00e0 excel\u00eancia e expertise no setor a tornam a escolha ideal para atender \u00e0s necessidades de seus clientes no mundo automotivo e industrial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toprelay.com.br\/en\/product\/tra821-324-reles-auxiliares\/\" \/>\n<meta property=\"og:site_name\" content=\"Top Relay\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-15T21:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/12\/TRA821.324.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/\",\"url\":\"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/\",\"name\":\"TRA821.324 - Rel\u00e9s Auxiliares - Top Relay\",\"isPartOf\":{\"@id\":\"https:\/\/toprelay.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/12\/TRA821.324.jpg\",\"datePublished\":\"2023-12-02T00:11:54+00:00\",\"dateModified\":\"2024-01-15T21:01:36+00:00\",\"description\":\"A Top Relay \u00e9 uma empresa l\u00edder na ind\u00fastria de rel\u00e9s, especializada em projetar, desenvolver, fabricar e testar uma ampla gama de produtos automotivos, agr\u00edcolas e industriais. Com foco em inova\u00e7\u00e3o e qualidade, a empresa oferece solu\u00e7\u00f5es abrangentes em rel\u00e9s, incluindo Minirreles, Rel\u00e9s Auxiliares, Rel\u00e9s de Farol, Rel\u00e9s de Pisca, Rel\u00e9s de Placa, Rel\u00e9s Eletr\u00f4nicos e Rel\u00e9s Soquetados. Sua dedica\u00e7\u00e3o \u00e0 excel\u00eancia e expertise no setor a tornam a escolha ideal para atender \u00e0s necessidades de seus clientes no mundo automotivo e industrial.\",\"breadcrumb\":{\"@id\":\"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#primaryimage\",\"url\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/12\/TRA821.324.jpg\",\"contentUrl\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/12\/TRA821.324.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/toprelay.com.br\/pt_br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\/\/toprelay.com.br\/loja\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TRA821.324 &#8211; Rel\u00e9s Auxiliares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/toprelay.com.br\/#website\",\"url\":\"https:\/\/toprelay.com.br\/\",\"name\":\"Top Relay\",\"description\":\"Rel\u00e9s Automotivos e Industriais\",\"publisher\":{\"@id\":\"https:\/\/toprelay.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/toprelay.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/toprelay.com.br\/#organization\",\"name\":\"Top Relay\",\"url\":\"https:\/\/toprelay.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/toprelay.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/08\/TOP-RELAY-LOGO-02.png\",\"contentUrl\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/08\/TOP-RELAY-LOGO-02.png\",\"width\":350,\"height\":71,\"caption\":\"Top Relay\"},\"image\":{\"@id\":\"https:\/\/toprelay.com.br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRA821.324 - Rel\u00e9s Auxiliares - Top Relay","description":"A Top Relay \u00e9 uma empresa l\u00edder na ind\u00fastria de rel\u00e9s, especializada em projetar, desenvolver, fabricar e testar uma ampla gama de produtos automotivos, agr\u00edcolas e industriais. Com foco em inova\u00e7\u00e3o e qualidade, a empresa oferece solu\u00e7\u00f5es abrangentes em rel\u00e9s, incluindo Minirreles, Rel\u00e9s Auxiliares, Rel\u00e9s de Farol, Rel\u00e9s de Pisca, Rel\u00e9s de Placa, Rel\u00e9s Eletr\u00f4nicos e Rel\u00e9s Soquetados. Sua dedica\u00e7\u00e3o \u00e0 excel\u00eancia e expertise no setor a tornam a escolha ideal para atender \u00e0s necessidades de seus clientes no mundo automotivo e industrial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toprelay.com.br\/en\/product\/tra821-324-reles-auxiliares\/","og_locale":"en_US","og_type":"article","og_title":"TRA821.324 - Rel\u00e9s Auxiliares - Top Relay","og_description":"A Top Relay \u00e9 uma empresa l\u00edder na ind\u00fastria de rel\u00e9s, especializada em projetar, desenvolver, fabricar e testar uma ampla gama de produtos automotivos, agr\u00edcolas e industriais. Com foco em inova\u00e7\u00e3o e qualidade, a empresa oferece solu\u00e7\u00f5es abrangentes em rel\u00e9s, incluindo Minirreles, Rel\u00e9s Auxiliares, Rel\u00e9s de Farol, Rel\u00e9s de Pisca, Rel\u00e9s de Placa, Rel\u00e9s Eletr\u00f4nicos e Rel\u00e9s Soquetados. Sua dedica\u00e7\u00e3o \u00e0 excel\u00eancia e expertise no setor a tornam a escolha ideal para atender \u00e0s necessidades de seus clientes no mundo automotivo e industrial.","og_url":"https:\/\/toprelay.com.br\/en\/product\/tra821-324-reles-auxiliares\/","og_site_name":"Top Relay","article_modified_time":"2024-01-15T21:01:36+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/12\/TRA821.324.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/","url":"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/","name":"TRA821.324 - Rel\u00e9s Auxiliares - Top Relay","isPartOf":{"@id":"https:\/\/toprelay.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#primaryimage"},"image":{"@id":"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#primaryimage"},"thumbnailUrl":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/12\/TRA821.324.jpg","datePublished":"2023-12-02T00:11:54+00:00","dateModified":"2024-01-15T21:01:36+00:00","description":"A Top Relay \u00e9 uma empresa l\u00edder na ind\u00fastria de rel\u00e9s, especializada em projetar, desenvolver, fabricar e testar uma ampla gama de produtos automotivos, agr\u00edcolas e industriais. Com foco em inova\u00e7\u00e3o e qualidade, a empresa oferece solu\u00e7\u00f5es abrangentes em rel\u00e9s, incluindo Minirreles, Rel\u00e9s Auxiliares, Rel\u00e9s de Farol, Rel\u00e9s de Pisca, Rel\u00e9s de Placa, Rel\u00e9s Eletr\u00f4nicos e Rel\u00e9s Soquetados. Sua dedica\u00e7\u00e3o \u00e0 excel\u00eancia e expertise no setor a tornam a escolha ideal para atender \u00e0s necessidades de seus clientes no mundo automotivo e industrial.","breadcrumb":{"@id":"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#primaryimage","url":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/12\/TRA821.324.jpg","contentUrl":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/12\/TRA821.324.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/toprelay.com.br\/produto\/tra821-324-reles-auxiliares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/toprelay.com.br\/pt_br\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/toprelay.com.br\/loja\/"},{"@type":"ListItem","position":3,"name":"TRA821.324 &#8211; Rel\u00e9s Auxiliares"}]},{"@type":"WebSite","@id":"https:\/\/toprelay.com.br\/#website","url":"https:\/\/toprelay.com.br\/","name":"Top Relay","description":"Rel\u00e9s Automotivos e Industriais","publisher":{"@id":"https:\/\/toprelay.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toprelay.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toprelay.com.br\/#organization","name":"Top Relay","url":"https:\/\/toprelay.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toprelay.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/08\/TOP-RELAY-LOGO-02.png","contentUrl":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/08\/TOP-RELAY-LOGO-02.png","width":350,"height":71,"caption":"Top Relay"},"image":{"@id":"https:\/\/toprelay.com.br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/product\/8388"}],"collection":[{"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/comments?post=8388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/media\/8408"}],"wp:attachment":[{"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/media?parent=8388"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=8388"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=8388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}