{"id":5754,"date":"2023-11-07T16:57:13","date_gmt":"2023-11-07T19:57:13","guid":{"rendered":"https:\/\/toprelay.com.br\/?post_type=product&#038;p=5754"},"modified":"2024-01-18T14:47:13","modified_gmt":"2024-01-18T17:47:13","slug":"tre700-200-centrais-eletricas","status":"publish","type":"product","link":"https:\/\/toprelay.com.br\/en\/product\/tre700-200-centrais-eletricas\/","title":{"rendered":"TRE700.200 \u2013 Circuit Boards"},"content":{"rendered":"<table id=\"tablepress-67\" class=\"tablepress tablepress-id-67 dataTable no-footer\">\n<thead>\n<tr class=\"row-1 odd\">\n<th class=\"column-1 sorting_disabled\" colspan=\"1\" rowspan=\"1\">Top Relay Code<\/th>\n<th class=\"column-2 sorting_disabled\" colspan=\"1\" rowspan=\"1\">O&amp;M Code<\/th>\n<th class=\"column-3 sorting_disabled\" colspan=\"1\" rowspan=\"1\">Assembler<\/th>\n<th class=\"column-4 sorting_disabled\" colspan=\"1\" rowspan=\"1\">Vehicles<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n<td class=\"column-1\">TRE700200<\/td>\n<td class=\"column-2\">290709<\/td>\n<td class=\"column-3\">Scania<\/td>\n<td class=\"column-4\">S\u00e9rie 2 at\u00e9 1997<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>CE 7002<\/p>\n<p>Centrais El\u00e9tricas | Centrales Electricas | Circuit Boards<\/p>","protected":false},"excerpt":{"rendered":"<p>C\u00f3digo Top Relay N. Original Montadora Ve\u00edculos TRE700200 290709 Scania S\u00e9rie 2 at\u00e9 1997 CE 7002 Centrais El\u00e9tricas | Centrales Electricas | Circuit Boards<\/p>","protected":false},"featured_media":5756,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}}},"product_cat":[3305,3264,3293],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TRE700.200 - Centrais El\u00e9tricas - Top Relay<\/title>\n<meta name=\"description\" content=\"A Top Relay especializada em projetar, desenvolver, fabricar e testar uma ampla gama de diversos produtos automotivos, agr\u00edcolas e industriais. Seu cat\u00e1logo de produtos diversos inclui itens como Abra\u00e7adeiras de Nylon, Antenas e Hastes, Bot\u00f5es de Parada Solicitada, Cabos para Baterias, Caixas de Diodo, Centrais El\u00e9tricas, Conversores e Estabilizadores de Tens\u00e3o, Espaguetes Corrugados, Fitas, Hor\u00edmetros Anal\u00f3gicos, L\u00e2mpadas LED, Lentes Indicadoras, Porta Fus\u00edveis, R\u00e9guas de Led, Sirenes, Soquetes, Terminais de Bateria e Termoretr\u00e1teis.Com um compromisso constante com a qualidade e a inova\u00e7\u00e3o, a Top Relay oferece solu\u00e7\u00f5es confi\u00e1veis para uma ampla gama de aplica\u00e7\u00f5es nos setores automotivo e industrial. Seja para melhorar a efici\u00eancia, a seguran\u00e7a ou a funcionalidade, os produtos diversos da Top Relay atendem \u00e0s demandas variadas de seus clientes e contribuem para o sucesso de seus projetos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toprelay.com.br\/en\/product\/tre700-200-centrais-eletricas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRE700.200 - Centrais El\u00e9tricas - Top Relay\" \/>\n<meta property=\"og:description\" content=\"A Top Relay especializada em projetar, desenvolver, fabricar e testar uma ampla gama de diversos produtos automotivos, agr\u00edcolas e industriais. Seu cat\u00e1logo de produtos diversos inclui itens como Abra\u00e7adeiras de Nylon, Antenas e Hastes, Bot\u00f5es de Parada Solicitada, Cabos para Baterias, Caixas de Diodo, Centrais El\u00e9tricas, Conversores e Estabilizadores de Tens\u00e3o, Espaguetes Corrugados, Fitas, Hor\u00edmetros Anal\u00f3gicos, L\u00e2mpadas LED, Lentes Indicadoras, Porta Fus\u00edveis, R\u00e9guas de Led, Sirenes, Soquetes, Terminais de Bateria e Termoretr\u00e1teis.Com um compromisso constante com a qualidade e a inova\u00e7\u00e3o, a Top Relay oferece solu\u00e7\u00f5es confi\u00e1veis para uma ampla gama de aplica\u00e7\u00f5es nos setores automotivo e industrial. Seja para melhorar a efici\u00eancia, a seguran\u00e7a ou a funcionalidade, os produtos diversos da Top Relay atendem \u00e0s demandas variadas de seus clientes e contribuem para o sucesso de seus projetos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toprelay.com.br\/en\/product\/tre700-200-centrais-eletricas\/\" \/>\n<meta property=\"og:site_name\" content=\"Top Relay\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-18T17:47:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/11\/TRE700.200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/\",\"url\":\"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/\",\"name\":\"TRE700.200 - Centrais El\u00e9tricas - Top Relay\",\"isPartOf\":{\"@id\":\"https:\/\/toprelay.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/11\/TRE700.200.jpg\",\"datePublished\":\"2023-11-07T19:57:13+00:00\",\"dateModified\":\"2024-01-18T17:47:13+00:00\",\"description\":\"A Top Relay especializada em projetar, desenvolver, fabricar e testar uma ampla gama de diversos produtos automotivos, agr\u00edcolas e industriais. Seu cat\u00e1logo de produtos diversos inclui itens como Abra\u00e7adeiras de Nylon, Antenas e Hastes, Bot\u00f5es de Parada Solicitada, Cabos para Baterias, Caixas de Diodo, Centrais El\u00e9tricas, Conversores e Estabilizadores de Tens\u00e3o, Espaguetes Corrugados, Fitas, Hor\u00edmetros Anal\u00f3gicos, L\u00e2mpadas LED, Lentes Indicadoras, Porta Fus\u00edveis, R\u00e9guas de Led, Sirenes, Soquetes, Terminais de Bateria e Termoretr\u00e1teis.Com um compromisso constante com a qualidade e a inova\u00e7\u00e3o, a Top Relay oferece solu\u00e7\u00f5es confi\u00e1veis para uma ampla gama de aplica\u00e7\u00f5es nos setores automotivo e industrial. Seja para melhorar a efici\u00eancia, a seguran\u00e7a ou a funcionalidade, os produtos diversos da Top Relay atendem \u00e0s demandas variadas de seus clientes e contribuem para o sucesso de seus projetos.\",\"breadcrumb\":{\"@id\":\"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#primaryimage\",\"url\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/11\/TRE700.200.jpg\",\"contentUrl\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/11\/TRE700.200.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/toprelay.com.br\/pt_br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\/\/toprelay.com.br\/loja\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TRE700.200 &#8211; Centrais El\u00e9tricas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/toprelay.com.br\/#website\",\"url\":\"https:\/\/toprelay.com.br\/\",\"name\":\"Top Relay\",\"description\":\"Rel\u00e9s Automotivos e Industriais\",\"publisher\":{\"@id\":\"https:\/\/toprelay.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/toprelay.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/toprelay.com.br\/#organization\",\"name\":\"Top Relay\",\"url\":\"https:\/\/toprelay.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/toprelay.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/08\/TOP-RELAY-LOGO-02.png\",\"contentUrl\":\"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/08\/TOP-RELAY-LOGO-02.png\",\"width\":350,\"height\":71,\"caption\":\"Top Relay\"},\"image\":{\"@id\":\"https:\/\/toprelay.com.br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRE700.200 - Centrais El\u00e9tricas - Top Relay","description":"A Top Relay especializada em projetar, desenvolver, fabricar e testar uma ampla gama de diversos produtos automotivos, agr\u00edcolas e industriais. Seu cat\u00e1logo de produtos diversos inclui itens como Abra\u00e7adeiras de Nylon, Antenas e Hastes, Bot\u00f5es de Parada Solicitada, Cabos para Baterias, Caixas de Diodo, Centrais El\u00e9tricas, Conversores e Estabilizadores de Tens\u00e3o, Espaguetes Corrugados, Fitas, Hor\u00edmetros Anal\u00f3gicos, L\u00e2mpadas LED, Lentes Indicadoras, Porta Fus\u00edveis, R\u00e9guas de Led, Sirenes, Soquetes, Terminais de Bateria e Termoretr\u00e1teis.Com um compromisso constante com a qualidade e a inova\u00e7\u00e3o, a Top Relay oferece solu\u00e7\u00f5es confi\u00e1veis para uma ampla gama de aplica\u00e7\u00f5es nos setores automotivo e industrial. Seja para melhorar a efici\u00eancia, a seguran\u00e7a ou a funcionalidade, os produtos diversos da Top Relay atendem \u00e0s demandas variadas de seus clientes e contribuem para o sucesso de seus projetos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toprelay.com.br\/en\/product\/tre700-200-centrais-eletricas\/","og_locale":"en_US","og_type":"article","og_title":"TRE700.200 - Centrais El\u00e9tricas - Top Relay","og_description":"A Top Relay especializada em projetar, desenvolver, fabricar e testar uma ampla gama de diversos produtos automotivos, agr\u00edcolas e industriais. Seu cat\u00e1logo de produtos diversos inclui itens como Abra\u00e7adeiras de Nylon, Antenas e Hastes, Bot\u00f5es de Parada Solicitada, Cabos para Baterias, Caixas de Diodo, Centrais El\u00e9tricas, Conversores e Estabilizadores de Tens\u00e3o, Espaguetes Corrugados, Fitas, Hor\u00edmetros Anal\u00f3gicos, L\u00e2mpadas LED, Lentes Indicadoras, Porta Fus\u00edveis, R\u00e9guas de Led, Sirenes, Soquetes, Terminais de Bateria e Termoretr\u00e1teis.Com um compromisso constante com a qualidade e a inova\u00e7\u00e3o, a Top Relay oferece solu\u00e7\u00f5es confi\u00e1veis para uma ampla gama de aplica\u00e7\u00f5es nos setores automotivo e industrial. Seja para melhorar a efici\u00eancia, a seguran\u00e7a ou a funcionalidade, os produtos diversos da Top Relay atendem \u00e0s demandas variadas de seus clientes e contribuem para o sucesso de seus projetos.","og_url":"https:\/\/toprelay.com.br\/en\/product\/tre700-200-centrais-eletricas\/","og_site_name":"Top Relay","article_modified_time":"2024-01-18T17:47:13+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/11\/TRE700.200.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/","url":"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/","name":"TRE700.200 - Centrais El\u00e9tricas - Top Relay","isPartOf":{"@id":"https:\/\/toprelay.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#primaryimage"},"image":{"@id":"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#primaryimage"},"thumbnailUrl":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/11\/TRE700.200.jpg","datePublished":"2023-11-07T19:57:13+00:00","dateModified":"2024-01-18T17:47:13+00:00","description":"A Top Relay especializada em projetar, desenvolver, fabricar e testar uma ampla gama de diversos produtos automotivos, agr\u00edcolas e industriais. Seu cat\u00e1logo de produtos diversos inclui itens como Abra\u00e7adeiras de Nylon, Antenas e Hastes, Bot\u00f5es de Parada Solicitada, Cabos para Baterias, Caixas de Diodo, Centrais El\u00e9tricas, Conversores e Estabilizadores de Tens\u00e3o, Espaguetes Corrugados, Fitas, Hor\u00edmetros Anal\u00f3gicos, L\u00e2mpadas LED, Lentes Indicadoras, Porta Fus\u00edveis, R\u00e9guas de Led, Sirenes, Soquetes, Terminais de Bateria e Termoretr\u00e1teis.Com um compromisso constante com a qualidade e a inova\u00e7\u00e3o, a Top Relay oferece solu\u00e7\u00f5es confi\u00e1veis para uma ampla gama de aplica\u00e7\u00f5es nos setores automotivo e industrial. Seja para melhorar a efici\u00eancia, a seguran\u00e7a ou a funcionalidade, os produtos diversos da Top Relay atendem \u00e0s demandas variadas de seus clientes e contribuem para o sucesso de seus projetos.","breadcrumb":{"@id":"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#primaryimage","url":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/11\/TRE700.200.jpg","contentUrl":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/11\/TRE700.200.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/toprelay.com.br\/produto\/tre700-200-centrais-eletricas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/toprelay.com.br\/pt_br\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/toprelay.com.br\/loja\/"},{"@type":"ListItem","position":3,"name":"TRE700.200 &#8211; Centrais El\u00e9tricas"}]},{"@type":"WebSite","@id":"https:\/\/toprelay.com.br\/#website","url":"https:\/\/toprelay.com.br\/","name":"Top Relay","description":"Rel\u00e9s Automotivos e Industriais","publisher":{"@id":"https:\/\/toprelay.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toprelay.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toprelay.com.br\/#organization","name":"Top Relay","url":"https:\/\/toprelay.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toprelay.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/08\/TOP-RELAY-LOGO-02.png","contentUrl":"https:\/\/toprelay.com.br\/wp-content\/uploads\/2023\/08\/TOP-RELAY-LOGO-02.png","width":350,"height":71,"caption":"Top Relay"},"image":{"@id":"https:\/\/toprelay.com.br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/product\/5754"}],"collection":[{"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/comments?post=5754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/media\/5756"}],"wp:attachment":[{"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/media?parent=5754"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=5754"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/toprelay.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=5754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}